{"id":1178,"date":"2017-03-09T15:38:05","date_gmt":"2017-03-09T14:38:05","guid":{"rendered":"http:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/"},"modified":"2026-04-13T17:19:14","modified_gmt":"2026-04-13T15:19:14","slug":"biothane-toejle-with-dubber-black","status":"publish","type":"product","link":"https:\/\/toelthester.dk\/en\/butik\/biothane-toejle-med-dubber-sort\/","title":{"rendered":"Biothane Rein With Studs black"},"content":{"rendered":"<p>This Bio bridle gives you an optimal feel with the horse, with studs that make it easy to hold on to.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>This Bio bridle gives you an optimal feel with the horse, with studs that make it easy to hold on to.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":8056,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":{"0":"post-1178","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-toejler","8":"first","9":"instock","10":"featured","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber.<\/title>\n<meta name=\"description\" content=\"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber der g\u00f8r at den er let at holde fast i.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toelthester.dk\/en\/store\/biothane-toejle-with-dubber-black\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber.\" \/>\n<meta property=\"og:description\" content=\"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber der g\u00f8r at den er let at holde fast i.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toelthester.dk\/en\/store\/biothane-toejle-with-dubber-black\/\" \/>\n<meta property=\"og:site_name\" content=\"Toelthester\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T15:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toelthester.dk\/wp-content\/uploads\/2019\/05\/T\u00f8lthester-396-72-dpi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/\",\"url\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/\",\"name\":\"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toelthester.dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/toelthester.dk\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/T\u00f8lthester-396-72-dpi.jpg\",\"datePublished\":\"2017-03-09T14:38:05+00:00\",\"dateModified\":\"2026-04-13T15:19:14+00:00\",\"description\":\"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber der g\u00f8r at den er let at holde fast i.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/#primaryimage\",\"url\":\"https:\\\/\\\/toelthester.dk\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/T\u00f8lthester-396-72-dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/toelthester.dk\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/T\u00f8lthester-396-72-dpi.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toelthester.dk\\\/butik\\\/biothane-toejle-med-dubber-sort\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/toelthester.dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/toelthester.dk\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biothane T\u00f8jle Med Dubber sort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toelthester.dk\\\/#website\",\"url\":\"https:\\\/\\\/toelthester.dk\\\/\",\"name\":\"Toelthester\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toelthester.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"This Bio bridle gives you an optimal feel with the horse, with studs.","description":"This Bio bridle gives you an optimal feel with the horse, with studs that make it easy to hold on to.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toelthester.dk\/en\/store\/biothane-toejle-with-dubber-black\/","og_locale":"en_GB","og_type":"article","og_title":"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber.","og_description":"Denne Bio t\u00f8jle giver dig en optimal f\u00f8ling med hesten, med dubber der g\u00f8r at den er let at holde fast i.","og_url":"https:\/\/toelthester.dk\/en\/store\/biothane-toejle-with-dubber-black\/","og_site_name":"Toelthester","article_modified_time":"2026-04-13T15:19:14+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/toelthester.dk\/wp-content\/uploads\/2019\/05\/T\u00f8lthester-396-72-dpi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/","url":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/","name":"This Bio bridle gives you an optimal feel with the horse, with studs.","isPartOf":{"@id":"https:\/\/toelthester.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/#primaryimage"},"image":{"@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/#primaryimage"},"thumbnailUrl":"https:\/\/toelthester.dk\/wp-content\/uploads\/2019\/05\/T\u00f8lthester-396-72-dpi.jpg","datePublished":"2017-03-09T14:38:05+00:00","dateModified":"2026-04-13T15:19:14+00:00","description":"This Bio bridle gives you an optimal feel with the horse, with studs that make it easy to hold on to.","breadcrumb":{"@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/#primaryimage","url":"https:\/\/toelthester.dk\/wp-content\/uploads\/2019\/05\/T\u00f8lthester-396-72-dpi.jpg","contentUrl":"https:\/\/toelthester.dk\/wp-content\/uploads\/2019\/05\/T\u00f8lthester-396-72-dpi.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/toelthester.dk\/butik\/biothane-toejle-med-dubber-sort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/toelthester.dk\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/toelthester.dk\/shop\/"},{"@type":"ListItem","position":3,"name":"Biothane T\u00f8jle Med Dubber sort"}]},{"@type":"WebSite","@id":"https:\/\/toelthester.dk\/#website","url":"https:\/\/toelthester.dk\/","name":"Toilet horses","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toelthester.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/product\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/media\/8056"}],"wp:attachment":[{"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/product_brand?post=1178"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/product_cat?post=1178"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/toelthester.dk\/en\/wp-json\/wp\/v2\/product_tag?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}